{"id":23401,"date":"2020-03-10T15:38:15","date_gmt":"2020-03-10T14:38:15","guid":{"rendered":"https:\/\/www.serhsserveis.com\/?p=23401"},"modified":"2023-04-26T19:52:31","modified_gmt":"2023-04-26T17:52:31","slug":"la-obligatoriedad-del-plan-de-igualdad-en-las-empresas","status":"publish","type":"post","link":"https:\/\/serhsserveis.com\/es\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\/","title":{"rendered":"La obligatoriedad del Plan de Igualdad en las empresas"},"content":{"rendered":"<h3>\u00bfConoces tus obligaciones frente una posible implantaci\u00f3n del Plan de Igualdad en tu empresa?<\/h3>\n<p>Desde el pasado 7 de marzo,\u00a0 todas las empresas con 150 o m\u00e1s trabajadores est\u00e1n obligadas a implantar un <strong>Plan de Igualdad<\/strong>, seg\u00fan se anunci\u00f3 en la publicaci\u00f3n en el BOE del Real Decreto Ley 6\/2019 con fecha 1 de marzo. En ella se exponen las medidas urgentes para garantizar la igualdad de trato y oportunidades entre hombres y mujeres en el trabajo y en la ocupaci\u00f3n.<\/p>\n<h4>\u00bfQu\u00e9 empresas tienen la obligaci\u00f3n de elaborar un Plan de Igualdad?<\/h4>\n<ol>\n<li>Aquellas que tengan equipos de 50 o m\u00e1s personas trabajando<\/li>\n<li>Si as\u00ed se establece en el convenio colectivo de aplicaci\u00f3n, en los t\u00e9rminos previstos en el mismo<\/li>\n<li>Cuando la autoridad laboral haya acordado en un procedimiento sancionador la sustituci\u00f3n de las sanciones accesorias para la elaboraci\u00f3n y la aplicaci\u00f3n de un plan, en los t\u00e9rminos que se fijen en el acuerdo indicado.<\/li>\n<\/ol>\n<p>La elaboraci\u00f3n e implantaci\u00f3n de planes de igualdad ser\u00e1 voluntaria para el resto de empresas, previa consulta en la representaci\u00f3n legal de los trabajadores y trabajadoras.<\/p>\n<p>Las consecuencias de no tener un plan de igualdad puede comportar <strong>\u00a0sanciones<\/strong> por falta <strong>grave<\/strong>, con multas de <strong>626 a 6.250 \u20ac,<\/strong> a falta <strong>muy grave<\/strong> , que va desde los <strong>6.251 \u20ac a los 187.515 \u20ac.<\/strong><\/p>\n<h4>\u00bfEn qu\u00e9 consiste un Plan de Igualdad?<\/h4>\n<p>Los planes de igualdad se consideran herramientas\u00a0 principales de intervenci\u00f3n en las empresas para poder afrontar toda una serie de desigualdades y discriminaciones que hoy d\u00eda contin\u00faan sufriendo las mujeres en los diferentes \u00e1mbitos sociales, de trabajo y ocupaci\u00f3n. Es la herramienta principal que permite garantizar los objetivos integrales de cualquier organizaci\u00f3n.<\/p>\n<p>Disponer de un Plan de Igualdad a medida de los valores de la misma entidad y equipos humanos es vital para garantizar el \u00e9xito social y productivo en las empresas.<\/p>\n<p>Consiste en:<\/p>\n<ul>\n<li>Un diagn\u00f3stico inicial donde analizar los siguientes apartados negociados: proceso de selecci\u00f3n y contrataci\u00f3n\/clasificaci\u00f3n profesional\/formaci\u00f3n; promoci\u00f3n profesional\/condiciones de trabajo, incluida la auditoria salarial entre mujeres y hombres\/ejercicio corresponsable de los derechos de la vida personal, familiar y laboral\/infrarepresentaci\u00f3n femenina\/retribuciones\/prevenci\u00f3n del acoso sexual y por raz\u00f3n de sexo.<\/li>\n<li>Un informe y planificaci\u00f3n de las medidas a implantar que garantizan y\/o fomentan la igualdad en oportunidad y desarrollo profesional entre hombres y mujeres.<\/li>\n<li>Un seguimiento y evaluaci\u00f3n peri\u00f3dicos.<\/li>\n<\/ul>\n<p>Desde la<a href=\"https:\/\/serhsserveis.com\/es\/prevencion-de-riesgos-laborales-y-asesores-en-inspecciones-de-trabajo\/\"> consultoria de prevenci\u00f3n de riesgos<\/a> <strong>elaboramos tu Plan de Igualdad, te asesoramos en la implantaci\u00f3n y en el seguimiento y evaluaci\u00f3n peri\u00f3dica<\/strong>.<\/p>\n<p style=\"text-align: center;\"><strong>En SERHS Serveis\u00a0 \u00abTe lo ponemos f\u00e1cil\u00bb. Solicita informaci\u00f3n en <a href=\"mailto:prevencioriscos@grupserhs.com\">prevencioriscos@grupserhs.com<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfConoces tus obligaciones frente una posible implantaci\u00f3n del Plan de Igualdad en tu empresa? Desde el pasado 7 de marzo,\u00a0 todas las empresas con 150 o m\u00e1s trabajadores est\u00e1n obligadas a implantar un Plan de Igualdad, seg\u00fan se anunci\u00f3 en la publicaci\u00f3n en el BOE del Real Decreto Ley 6\/2019 con fecha 1 de marzo.<\/p>\n","protected":false},"author":10,"featured_media":23399,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85,65],"tags":[],"class_list":["post-23401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es","category-consultoria-serhs-prevencion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La obligatoriedad del Plan de Igualdad en las empresas<\/title>\n<meta name=\"description\" content=\"Desde el pasado 7 de marzo,\u00a0 todas las empresas con 150 o m\u00e1s trabajadores est\u00e1n obligadas a implantar un Plan de Igualdad, donde se garantice la igualdad de g\u00e9nero.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/serhsserveis.com\/es\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La obligatoriedad del Plan de Igualdad en las empresas\" \/>\n<meta property=\"og:description\" content=\"Desde el pasado 7 de marzo,\u00a0 todas las empresas con 150 o m\u00e1s trabajadores est\u00e1n obligadas a implantar un Plan de Igualdad, donde se garantice la igualdad de g\u00e9nero.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/serhsserveis.com\/es\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\/\" \/>\n<meta property=\"og:site_name\" content=\"SERHS Serveis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SERHS-Serveis-914835645340740\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-10T14:38:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-26T17:52:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/serhsserveis.com\/wp-content\/uploads\/2020\/03\/Pla-Igualtat.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"665\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"rf\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rf\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\\\/\"},\"author\":{\"name\":\"rf\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#\\\/schema\\\/person\\\/ed29406fe23d106405df24b321e0be26\"},\"headline\":\"La obligatoriedad del Plan de Igualdad en las empresas\",\"datePublished\":\"2020-03-10T14:38:15+00:00\",\"dateModified\":\"2023-04-26T17:52:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\\\/\"},\"wordCount\":465,\"publisher\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serhsserveis.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Pla-Igualtat.png\",\"articleSection\":[\"BLOG\",\"Consultoria SERHS Prevenci\u00f3\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\\\/\",\"url\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\\\/\",\"name\":\"La obligatoriedad del Plan de Igualdad en las empresas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serhsserveis.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Pla-Igualtat.png\",\"datePublished\":\"2020-03-10T14:38:15+00:00\",\"dateModified\":\"2023-04-26T17:52:31+00:00\",\"description\":\"Desde el pasado 7 de marzo,\u00a0 todas las empresas con 150 o m\u00e1s trabajadores est\u00e1n obligadas a implantar un Plan de Igualdad, donde se garantice la igualdad de g\u00e9nero.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/serhsserveis.com\\\/es\\\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/serhsserveis.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Pla-Igualtat.png\",\"contentUrl\":\"https:\\\/\\\/serhsserveis.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Pla-Igualtat.png\",\"width\":1000,\"height\":665,\"caption\":\"Pla Igualtat empreses\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La obligatoriedad del Plan de Igualdad en las empresas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#website\",\"url\":\"https:\\\/\\\/serhsserveis.com\\\/\",\"name\":\"SERHS Serveis\",\"description\":\"T&#039;ho posa f\u00e0cil\",\"publisher\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/serhsserveis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#organization\",\"name\":\"SERHS Serveis\",\"url\":\"https:\\\/\\\/serhsserveis.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/serhsserveis.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/Logo-SERHS-Serveis-Serveis-integrals.png\",\"contentUrl\":\"https:\\\/\\\/serhsserveis.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/Logo-SERHS-Serveis-Serveis-integrals.png\",\"width\":120,\"height\":40,\"caption\":\"SERHS Serveis\"},\"image\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SERHS-Serveis-914835645340740\\\/\",\"https:\\\/\\\/www.instagram.com\\\/serhsserveis\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/serhs-serveis\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCyY1p4E94vhubNiJb8yESgQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#\\\/schema\\\/person\\\/ed29406fe23d106405df24b321e0be26\",\"name\":\"rf\",\"url\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/author\\\/rf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La obligatoriedad del Plan de Igualdad en las empresas","description":"Desde el pasado 7 de marzo,\u00a0 todas las empresas con 150 o m\u00e1s trabajadores est\u00e1n obligadas a implantar un Plan de Igualdad, donde se garantice la igualdad de g\u00e9nero.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/serhsserveis.com\/es\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\/","og_locale":"es_ES","og_type":"article","og_title":"La obligatoriedad del Plan de Igualdad en las empresas","og_description":"Desde el pasado 7 de marzo,\u00a0 todas las empresas con 150 o m\u00e1s trabajadores est\u00e1n obligadas a implantar un Plan de Igualdad, donde se garantice la igualdad de g\u00e9nero.","og_url":"https:\/\/serhsserveis.com\/es\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\/","og_site_name":"SERHS Serveis","article_publisher":"https:\/\/www.facebook.com\/SERHS-Serveis-914835645340740\/","article_published_time":"2020-03-10T14:38:15+00:00","article_modified_time":"2023-04-26T17:52:31+00:00","og_image":[{"width":1000,"height":665,"url":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2020\/03\/Pla-Igualtat.png","type":"image\/png"}],"author":"rf","twitter_misc":{"Escrito por":"rf","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/serhsserveis.com\/es\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\/#article","isPartOf":{"@id":"https:\/\/serhsserveis.com\/es\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\/"},"author":{"name":"rf","@id":"https:\/\/serhsserveis.com\/#\/schema\/person\/ed29406fe23d106405df24b321e0be26"},"headline":"La obligatoriedad del Plan de Igualdad en las empresas","datePublished":"2020-03-10T14:38:15+00:00","dateModified":"2023-04-26T17:52:31+00:00","mainEntityOfPage":{"@id":"https:\/\/serhsserveis.com\/es\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\/"},"wordCount":465,"publisher":{"@id":"https:\/\/serhsserveis.com\/#organization"},"image":{"@id":"https:\/\/serhsserveis.com\/es\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\/#primaryimage"},"thumbnailUrl":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2020\/03\/Pla-Igualtat.png","articleSection":["BLOG","Consultoria SERHS Prevenci\u00f3"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/serhsserveis.com\/es\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\/","url":"https:\/\/serhsserveis.com\/es\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\/","name":"La obligatoriedad del Plan de Igualdad en las empresas","isPartOf":{"@id":"https:\/\/serhsserveis.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/serhsserveis.com\/es\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\/#primaryimage"},"image":{"@id":"https:\/\/serhsserveis.com\/es\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\/#primaryimage"},"thumbnailUrl":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2020\/03\/Pla-Igualtat.png","datePublished":"2020-03-10T14:38:15+00:00","dateModified":"2023-04-26T17:52:31+00:00","description":"Desde el pasado 7 de marzo,\u00a0 todas las empresas con 150 o m\u00e1s trabajadores est\u00e1n obligadas a implantar un Plan de Igualdad, donde se garantice la igualdad de g\u00e9nero.","breadcrumb":{"@id":"https:\/\/serhsserveis.com\/es\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/serhsserveis.com\/es\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/serhsserveis.com\/es\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\/#primaryimage","url":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2020\/03\/Pla-Igualtat.png","contentUrl":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2020\/03\/Pla-Igualtat.png","width":1000,"height":665,"caption":"Pla Igualtat empreses"},{"@type":"BreadcrumbList","@id":"https:\/\/serhsserveis.com\/es\/la-obligatoriedad-del-plan-de-igualdad-en-las-empresas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/serhsserveis.com\/es\/"},{"@type":"ListItem","position":2,"name":"La obligatoriedad del Plan de Igualdad en las empresas"}]},{"@type":"WebSite","@id":"https:\/\/serhsserveis.com\/#website","url":"https:\/\/serhsserveis.com\/","name":"SERHS Serveis","description":"T&#039;ho posa f\u00e0cil","publisher":{"@id":"https:\/\/serhsserveis.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/serhsserveis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/serhsserveis.com\/#organization","name":"SERHS Serveis","url":"https:\/\/serhsserveis.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/serhsserveis.com\/#\/schema\/logo\/image\/","url":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2017\/09\/Logo-SERHS-Serveis-Serveis-integrals.png","contentUrl":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2017\/09\/Logo-SERHS-Serveis-Serveis-integrals.png","width":120,"height":40,"caption":"SERHS Serveis"},"image":{"@id":"https:\/\/serhsserveis.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SERHS-Serveis-914835645340740\/","https:\/\/www.instagram.com\/serhsserveis\/","https:\/\/www.linkedin.com\/company\/serhs-serveis","https:\/\/www.youtube.com\/channel\/UCyY1p4E94vhubNiJb8yESgQ"]},{"@type":"Person","@id":"https:\/\/serhsserveis.com\/#\/schema\/person\/ed29406fe23d106405df24b321e0be26","name":"rf","url":"https:\/\/serhsserveis.com\/es\/author\/rf\/"}]}},"jetpack_featured_media_url":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2020\/03\/Pla-Igualtat.png","_links":{"self":[{"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/posts\/23401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/comments?post=23401"}],"version-history":[{"count":1,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/posts\/23401\/revisions"}],"predecessor-version":[{"id":29821,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/posts\/23401\/revisions\/29821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/media\/23399"}],"wp:attachment":[{"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/media?parent=23401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/categories?post=23401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/tags?post=23401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}