{"id":3917,"date":"2017-12-01T16:49:52","date_gmt":"2017-12-01T15:49:52","guid":{"rendered":"https:\/\/www.serhsserveis.com\/?p=3917"},"modified":"2023-04-26T19:53:43","modified_gmt":"2023-04-26T17:53:43","slug":"permisos-elecciones-parlamento-cataluna","status":"publish","type":"post","link":"https:\/\/serhsserveis.com\/es\/permisos-elecciones-parlamento-cataluna\/","title":{"rendered":"Permisos elecciones al Parlamento de Catalu\u00f1a"},"content":{"rendered":"<p>El 21 de Diciembre se celebran elecciones en el Parlamento de Catalu\u00f1a. Desde <a href=\"https:\/\/serhsserveis.com\/es\/gestoria-fiscal-y-laboral-servicio-juridico-nomina-renta-y-prevencion\/\"><strong><span style=\"color: #66008c;\">SERHS Serveis Gestiona<\/span><\/strong><\/a> ponemos a tu disposici\u00f3n toda la informaci\u00f3n sobre los derechos y permisos de participaci\u00f3n. Te lo explicamos todo :<\/p>\n<ol>\n<li><strong>Duraci\u00f3n del permiso de los trabajadores\/as para ir a votar<\/strong>:<\/li>\n<\/ol>\n<p>Las empresas conceder\u00e1n a los trabajadores \/ as que ostenten la condici\u00f3n de electores y tengan obligaci\u00f3n de trabajar en esta fecha, un permiso de hasta cuatro horas dentro de la jornada laboral<br \/>\nque les corresponda.<\/p>\n<p>Si la coincidencia de la jornada laboral con el horario de apertura de los colegios electorales es como m\u00e1ximo de dos horas, no ser\u00e1 necesario conceder dicho permiso a los trabajadores; si es de m\u00e1s de dos horas y menos de cuatro, se conceder\u00e1 una licencia de dos horas, y si esta coincidencia es de cuatro o m\u00e1s horas, se conceder\u00e1 el permiso general de 4 horas.<\/p>\n<p>Se reducir\u00e1 proporcionalmente la duraci\u00f3n del permiso mencionado a los trabajadores que el d\u00eda de la votaci\u00f3n realicen una jornada inferior a la habitual, legal o convenida.<\/p>\n<p>Los trabajadores que tengan una jornada cuyo horario no coincida ni total ni parcialmente con el de los colegios electorales no tendr\u00e1n derecho a ning\u00fan permiso.<\/p>\n<p>Los empresarios pueden solicitar a sus trabajadores la exhibici\u00f3n del justificante acreditativo de haber votado, expedido por la mesa electoral correspondiente.<\/p>\n<p>Este permiso no deber\u00e1 recuperarse y se retribuir\u00e1 con el salario que corresponder\u00eda al trabajador si hubiera prestado sus servicios normalmente.<\/p>\n<p>La determinaci\u00f3n del momento de utilizaci\u00f3n de las horas concedidas para la votaci\u00f3n, que debe coincidir con el horario establecido por el colegio electoral, es potestad del empresario.<\/p>\n<p>2. <strong>Permiso para los trabajadores\/as que acrediten la condici\u00f3n de miembros de la mesa, interventores o apoderados.<\/strong><\/p>\n<p>En cuanto a los trabajadores que acrediten la condici\u00f3n de miembros de mesa electoral o de interventores y que NO disfruten de descanso el d\u00eda de la votaci\u00f3n, se les conceder\u00e1 el permiso<br \/>\ncorrespondiente a la jornada completa del d\u00eda mencionado y, adem\u00e1s, un permiso correspondiente a las cinco primeras horas de la jornada laboral del d\u00eda inmediatamente posterior.<\/p>\n<p>Los que acrediten la misma condici\u00f3n, y SI disfruten del descanso el d\u00eda de la votaci\u00f3n, tienen derecho a un permiso retribuido de las cinco primeras horas durante la jornada del d\u00eda<br \/>\ninmediatamente posterior al de la votaci\u00f3n.<\/p>\n<p>Los trabajadores que acrediten la condici\u00f3n de apoderados y que no disfruten de descanso el d\u00eda de la votaci\u00f3n tienen derecho a un permiso retribuido durante este d\u00eda.<\/p>\n<p>Estos permisos, de car\u00e1cter no recuperable, ser\u00e1n retribuidos por la empresa una vez justificada la actuaci\u00f3n como miembro de mesa, interventor o apoderado.<\/p>\n<p>3. <strong>Posibilidad de cambio de turno<\/strong>.<\/p>\n<p>Los trabajadores que sean miembros de mesa electoral o apoderados y tengan que trabajar en el turno de noche de la fecha inmediatamente anterior a la jornada electoral, podr\u00e1n solicitar al<br \/>\nempresario un cambio de turno que les permita descansar la noche antes de las elecciones . La empresa deber\u00e1 aceptar esta petici\u00f3n.<\/p>\n<p>En caso de duda, puedes ponerte en contacto con el departamento de Servicios jur\u00eddico-laborales.<\/p>\n<h6>Normativa<br \/>\nReal Decreto 953\/2017, de 31 de Octubre por el cu\u00e1l se dictan normas complementarias para la realizaci\u00f3n de las \u200b\u200belecciones\u200b\u200b al\u200b\u200b Parlamento\u200b\u200b de\u200b\u200b Catalu\u00f1a \u200b\u200b2017.<br \/>\nPublicado \u200b\u200ben \u200b\u200bel\u200b\u200b\u200b B.O.E.\u200b\u200b03\/11\/2017\u200b\u200b y \u200b\u200btambi\u00e9n\u200b\u200b\u200b (\u200b\u200bid\u00e9ntico \u200b\u200bcontenido\u200b\u200b) \u200b\u200ben \u200b\u200bel\u200b\u200b D.O.G.C. \u200b\u200bde\u200b\u200b 06\/11\/2017.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El 21 de Diciembre se celebran elecciones en el Parlamento de Catalu\u00f1a. Desde SERHS Serveis Gestiona ponemos a tu disposici\u00f3n toda la informaci\u00f3n sobre los derechos y permisos de participaci\u00f3n. Te lo explicamos todo : Duraci\u00f3n del permiso de los trabajadores\/as para ir a votar: Las empresas conceder\u00e1n a los trabajadores \/ as que ostenten<\/p>\n","protected":false},"author":10,"featured_media":4173,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61,47],"tags":[],"class_list":["post-3917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-asesoria-juridica-laboral","category-noticias-serhs-serveis-gestiona"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Permisos elecciones al Parlamento de Catalu\u00f1a<\/title>\n<meta name=\"description\" content=\"El 21 de Diciembre se celebran elecciones en el Parlamento de Catalu\u00f1a. Desde SERHS Serveis Gestiona ponemos a tu disposici\u00f3n toda la informaci\u00f3n sobre los derechos y permisos de participaci\u00f3n. Te lo explicamos todo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/serhsserveis.com\/es\/permisos-elecciones-parlamento-cataluna\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Permisos elecciones al Parlamento de Catalu\u00f1a\" \/>\n<meta property=\"og:description\" content=\"El 21 de Diciembre se celebran elecciones en el Parlamento de Catalu\u00f1a. Desde SERHS Serveis Gestiona ponemos a tu disposici\u00f3n toda la informaci\u00f3n sobre los derechos y permisos de participaci\u00f3n. Te lo explicamos todo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/serhsserveis.com\/es\/permisos-elecciones-parlamento-cataluna\/\" \/>\n<meta property=\"og:site_name\" content=\"SERHS Serveis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SERHS-Serveis-914835645340740\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-01T15:49:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-26T17:53:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/serhsserveis.com\/wp-content\/uploads\/2017\/12\/Permisos-elecciones-al-Parlamento-de-Cataluna.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"420\" \/>\n\t<meta property=\"og:image:height\" content=\"240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rf\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rf\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/permisos-elecciones-parlamento-cataluna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/permisos-elecciones-parlamento-cataluna\\\/\"},\"author\":{\"name\":\"rf\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#\\\/schema\\\/person\\\/ed29406fe23d106405df24b321e0be26\"},\"headline\":\"Permisos elecciones al Parlamento de Catalu\u00f1a\",\"datePublished\":\"2017-12-01T15:49:52+00:00\",\"dateModified\":\"2023-04-26T17:53:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/permisos-elecciones-parlamento-cataluna\\\/\"},\"wordCount\":599,\"publisher\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/permisos-elecciones-parlamento-cataluna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serhsserveis.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Permisos-elecciones-al-Parlamento-de-Cataluna.jpg\",\"articleSection\":[\"Asesor\u00eda jur\u00eddica-laboral\",\"SERHS Serveis Gestiona\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/permisos-elecciones-parlamento-cataluna\\\/\",\"url\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/permisos-elecciones-parlamento-cataluna\\\/\",\"name\":\"Permisos elecciones al Parlamento de Catalu\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/permisos-elecciones-parlamento-cataluna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/permisos-elecciones-parlamento-cataluna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serhsserveis.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Permisos-elecciones-al-Parlamento-de-Cataluna.jpg\",\"datePublished\":\"2017-12-01T15:49:52+00:00\",\"dateModified\":\"2023-04-26T17:53:43+00:00\",\"description\":\"El 21 de Diciembre se celebran elecciones en el Parlamento de Catalu\u00f1a. Desde SERHS Serveis Gestiona ponemos a tu disposici\u00f3n toda la informaci\u00f3n sobre los derechos y permisos de participaci\u00f3n. Te lo explicamos todo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/permisos-elecciones-parlamento-cataluna\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/serhsserveis.com\\\/es\\\/permisos-elecciones-parlamento-cataluna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/permisos-elecciones-parlamento-cataluna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/serhsserveis.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Permisos-elecciones-al-Parlamento-de-Cataluna.jpg\",\"contentUrl\":\"https:\\\/\\\/serhsserveis.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/Permisos-elecciones-al-Parlamento-de-Cataluna.jpg\",\"width\":420,\"height\":240,\"caption\":\"Eleccions\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/permisos-elecciones-parlamento-cataluna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Permisos elecciones al Parlamento de Catalu\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#website\",\"url\":\"https:\\\/\\\/serhsserveis.com\\\/\",\"name\":\"SERHS Serveis\",\"description\":\"T&#039;ho posa f\u00e0cil\",\"publisher\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/serhsserveis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#organization\",\"name\":\"SERHS Serveis\",\"url\":\"https:\\\/\\\/serhsserveis.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/serhsserveis.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/Logo-SERHS-Serveis-Serveis-integrals.png\",\"contentUrl\":\"https:\\\/\\\/serhsserveis.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/Logo-SERHS-Serveis-Serveis-integrals.png\",\"width\":120,\"height\":40,\"caption\":\"SERHS Serveis\"},\"image\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SERHS-Serveis-914835645340740\\\/\",\"https:\\\/\\\/www.instagram.com\\\/serhsserveis\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/serhs-serveis\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCyY1p4E94vhubNiJb8yESgQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#\\\/schema\\\/person\\\/ed29406fe23d106405df24b321e0be26\",\"name\":\"rf\",\"url\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/author\\\/rf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Permisos elecciones al Parlamento de Catalu\u00f1a","description":"El 21 de Diciembre se celebran elecciones en el Parlamento de Catalu\u00f1a. Desde SERHS Serveis Gestiona ponemos a tu disposici\u00f3n toda la informaci\u00f3n sobre los derechos y permisos de participaci\u00f3n. Te lo explicamos todo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/serhsserveis.com\/es\/permisos-elecciones-parlamento-cataluna\/","og_locale":"es_ES","og_type":"article","og_title":"Permisos elecciones al Parlamento de Catalu\u00f1a","og_description":"El 21 de Diciembre se celebran elecciones en el Parlamento de Catalu\u00f1a. Desde SERHS Serveis Gestiona ponemos a tu disposici\u00f3n toda la informaci\u00f3n sobre los derechos y permisos de participaci\u00f3n. Te lo explicamos todo.","og_url":"https:\/\/serhsserveis.com\/es\/permisos-elecciones-parlamento-cataluna\/","og_site_name":"SERHS Serveis","article_publisher":"https:\/\/www.facebook.com\/SERHS-Serveis-914835645340740\/","article_published_time":"2017-12-01T15:49:52+00:00","article_modified_time":"2023-04-26T17:53:43+00:00","og_image":[{"width":420,"height":240,"url":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2017\/12\/Permisos-elecciones-al-Parlamento-de-Cataluna.jpg","type":"image\/jpeg"}],"author":"rf","twitter_misc":{"Escrito por":"rf","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/serhsserveis.com\/es\/permisos-elecciones-parlamento-cataluna\/#article","isPartOf":{"@id":"https:\/\/serhsserveis.com\/es\/permisos-elecciones-parlamento-cataluna\/"},"author":{"name":"rf","@id":"https:\/\/serhsserveis.com\/#\/schema\/person\/ed29406fe23d106405df24b321e0be26"},"headline":"Permisos elecciones al Parlamento de Catalu\u00f1a","datePublished":"2017-12-01T15:49:52+00:00","dateModified":"2023-04-26T17:53:43+00:00","mainEntityOfPage":{"@id":"https:\/\/serhsserveis.com\/es\/permisos-elecciones-parlamento-cataluna\/"},"wordCount":599,"publisher":{"@id":"https:\/\/serhsserveis.com\/#organization"},"image":{"@id":"https:\/\/serhsserveis.com\/es\/permisos-elecciones-parlamento-cataluna\/#primaryimage"},"thumbnailUrl":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2017\/12\/Permisos-elecciones-al-Parlamento-de-Cataluna.jpg","articleSection":["Asesor\u00eda jur\u00eddica-laboral","SERHS Serveis Gestiona"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/serhsserveis.com\/es\/permisos-elecciones-parlamento-cataluna\/","url":"https:\/\/serhsserveis.com\/es\/permisos-elecciones-parlamento-cataluna\/","name":"Permisos elecciones al Parlamento de Catalu\u00f1a","isPartOf":{"@id":"https:\/\/serhsserveis.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/serhsserveis.com\/es\/permisos-elecciones-parlamento-cataluna\/#primaryimage"},"image":{"@id":"https:\/\/serhsserveis.com\/es\/permisos-elecciones-parlamento-cataluna\/#primaryimage"},"thumbnailUrl":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2017\/12\/Permisos-elecciones-al-Parlamento-de-Cataluna.jpg","datePublished":"2017-12-01T15:49:52+00:00","dateModified":"2023-04-26T17:53:43+00:00","description":"El 21 de Diciembre se celebran elecciones en el Parlamento de Catalu\u00f1a. Desde SERHS Serveis Gestiona ponemos a tu disposici\u00f3n toda la informaci\u00f3n sobre los derechos y permisos de participaci\u00f3n. Te lo explicamos todo.","breadcrumb":{"@id":"https:\/\/serhsserveis.com\/es\/permisos-elecciones-parlamento-cataluna\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/serhsserveis.com\/es\/permisos-elecciones-parlamento-cataluna\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/serhsserveis.com\/es\/permisos-elecciones-parlamento-cataluna\/#primaryimage","url":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2017\/12\/Permisos-elecciones-al-Parlamento-de-Cataluna.jpg","contentUrl":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2017\/12\/Permisos-elecciones-al-Parlamento-de-Cataluna.jpg","width":420,"height":240,"caption":"Eleccions"},{"@type":"BreadcrumbList","@id":"https:\/\/serhsserveis.com\/es\/permisos-elecciones-parlamento-cataluna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/serhsserveis.com\/es\/"},{"@type":"ListItem","position":2,"name":"Permisos elecciones al Parlamento de Catalu\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/serhsserveis.com\/#website","url":"https:\/\/serhsserveis.com\/","name":"SERHS Serveis","description":"T&#039;ho posa f\u00e0cil","publisher":{"@id":"https:\/\/serhsserveis.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/serhsserveis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/serhsserveis.com\/#organization","name":"SERHS Serveis","url":"https:\/\/serhsserveis.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/serhsserveis.com\/#\/schema\/logo\/image\/","url":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2017\/09\/Logo-SERHS-Serveis-Serveis-integrals.png","contentUrl":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2017\/09\/Logo-SERHS-Serveis-Serveis-integrals.png","width":120,"height":40,"caption":"SERHS Serveis"},"image":{"@id":"https:\/\/serhsserveis.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SERHS-Serveis-914835645340740\/","https:\/\/www.instagram.com\/serhsserveis\/","https:\/\/www.linkedin.com\/company\/serhs-serveis","https:\/\/www.youtube.com\/channel\/UCyY1p4E94vhubNiJb8yESgQ"]},{"@type":"Person","@id":"https:\/\/serhsserveis.com\/#\/schema\/person\/ed29406fe23d106405df24b321e0be26","name":"rf","url":"https:\/\/serhsserveis.com\/es\/author\/rf\/"}]}},"jetpack_featured_media_url":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2017\/12\/Permisos-elecciones-al-Parlamento-de-Cataluna.jpg","_links":{"self":[{"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/posts\/3917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/comments?post=3917"}],"version-history":[{"count":1,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/posts\/3917\/revisions"}],"predecessor-version":[{"id":30065,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/posts\/3917\/revisions\/30065"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/media\/4173"}],"wp:attachment":[{"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/media?parent=3917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/categories?post=3917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/tags?post=3917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}