{"id":4573,"date":"2018-04-05T20:06:47","date_gmt":"2018-04-05T18:06:47","guid":{"rendered":"https:\/\/www.serhsserveis.com\/?p=4573"},"modified":"2019-06-03T11:57:51","modified_gmt":"2019-06-03T09:57:51","slug":"vender-servicios-sentimientos-valores-experiencias","status":"publish","type":"post","link":"https:\/\/serhsserveis.com\/es\/vender-servicios-sentimientos-valores-experiencias\/","title":{"rendered":"Vender Servicios, sentimientos, valores, experiencias"},"content":{"rendered":"<p>Hoy en d\u00eda todos pensamos que dedicarse a vender es f\u00e1cil; un poco de esfuerzo y \u201cdon de palabra\u201d y \u00a1listo!. Y si adem\u00e1s disponemos de productos potentes y con vagaje y reconocimiento en el mercado, \u00a1todav\u00eda m\u00e1s f\u00e1cil!<\/p>\n<p>Pero, \u00bfy si hemos de ir m\u00e1s all\u00e0? \u00bfY si nuestras ventas no son materiales? \u00bfY si nos dedicamos a vender intangibles? En este sentido hemos de ir un paso m\u00e1s all\u00e1, pues adem\u00e1s de vender atributos hemos de ser capaces de vender \u201cvalores, experiencias, sentimientos,&#8230;\u201d.<\/p>\n<p>Es por ello que, para SERHS Serveis, nuestro misi\u00f3n se postula en convertirnos en el compa\u00f1ero de viaje y aventuras de nuestro cliente. Estamos a su lado, lo escuchamos, lo acompa\u00f1amos en todas las necesidades seg\u00fan sea el momento.<\/p>\n<p>Qu\u00e9 hace que en SERHS Serveis \u201cTe lo pongamos f\u00e1cil\u201d. Que \u201cvendemos\u201d realmente a nuestro cliente:<\/p>\n<p><b>1. Generamos confianza.\u00a0<\/b>Confiamos en nuestros valores, en nuestro talento, en nuestras personas. Por ello, apostamos por el bienestar por encima de cualquier inter\u00e9s econ\u00f3mico.<\/p>\n<p><b>2. Creamos valor.<\/b>\u00a0Apostamos por nuevos retos y trabajamos con esfuerzo para conseguir la excelencia.<\/p>\n<p><b>3. Somos transparentes.\u00a0<\/b>Nos preocupamos de ofrecer el mejor servicio con la mejor calidad, evaluando posibles riesgos y ofreciendo abiertamente a nuestro cliente nuestras aptitudes e inquietudes. La transparencia en ella misma nos permitir\u00e1 obtener la confianza de nuestro p\u00fablico.<\/p>\n<p><b>4. Nos rodeamos de profesionales,<\/b>\u00a0que conocen sus aptitudes, que quieren satisfacer las necesidades de nuestro cliente; su bienestar y tranquilidad, y no el cierre de la venta, se convierten en las prioridades de nuestros equipos.<\/p>\n<p><b>5. Experiencia.<\/b>\u00a0M\u00e1s de 30 a\u00f1os de experiencia en el sector de la gestoria, nuevas tecnolog\u00edas y restauraci\u00f3n nos avalan.<\/p>\n<p><b>6. Conocemos las \u00faltimas tendencias<\/b>\u00a0en las diferentes tipolog\u00edas de servicios a los que nos dirigimos. Estamos en continua formaci\u00f3n y b\u00fasqueda de mejoras para llegar all\u00ed donde nuestro cliente necesita.<\/p>\n<p><b>7. Servicio.<\/b>\u00a0Vamos m\u00e1s all\u00e1. Ofrecemos confianza, atenci\u00f3n y ayuda personalizadas para que nuestro cliente nos vea realmente como su \u201ccompa\u00f1ero de viaje\u201d.<\/p>\n<p><b>8. Credibilidad.\u00a0<\/b>Apostamos por la tranquilidad, por las cosas bien hechas. Ayudamos a la persona que opta por asumir nuevos riesgos y la acompa\u00f1amos en toda esa nueva etapa.<\/p>\n<p><b>9. Orientaci\u00f3n.\u00a0<\/b>Atendemos, escuchamos. Orientamos en base al objetivo de nuevas acciones, buscando siempre la satisfacci\u00f3n y bienestar por encima de los intereses econ\u00f3micos.<\/p>\n<p><b>10. Renovaci\u00f3n constante.<\/b>\u00a0No paramos. Cada d\u00eda es un nuevo reto a partir del cual ponemos en marcha nuevos mecanismos que nos permitan ofrecer el servicio m\u00e1s \u00f3ptimo y con la mejor calidad del mercado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy en d\u00eda todos pensamos que dedicarse a vender es f\u00e1cil; un poco de esfuerzo y \u201cdon de palabra\u201d y \u00a1listo!. Y si adem\u00e1s disponemos de productos potentes y con vagaje y reconocimiento en el mercado, \u00a1todav\u00eda m\u00e1s f\u00e1cil! Pero, \u00bfy si hemos de ir m\u00e1s all\u00e0? \u00bfY si nuestras ventas no son materiales? \u00bfY<\/p>\n","protected":false},"author":10,"featured_media":4602,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85,63],"tags":[89,90,91],"class_list":["post-4573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es","category-gestioon-de-personas","tag-sentimientos","tag-valores","tag-venta-de-servicios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vender Servicios, sentimientos, valores, experiencias<\/title>\n<meta name=\"description\" content=\"Campa\u00f1a de la renta 2017-2018. Haz la renta y consigue descuentos en seguros, servicios fiscal-contables y nuevas tecnolog\u00edas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/serhsserveis.com\/es\/vender-servicios-sentimientos-valores-experiencias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vender Servicios, sentimientos, valores, experiencias\" \/>\n<meta property=\"og:description\" content=\"Campa\u00f1a de la renta 2017-2018. Haz la renta y consigue descuentos en seguros, servicios fiscal-contables y nuevas tecnolog\u00edas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/serhsserveis.com\/es\/vender-servicios-sentimientos-valores-experiencias\/\" \/>\n<meta property=\"og:site_name\" content=\"SERHS Serveis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SERHS-Serveis-914835645340740\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-05T18:06:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-03T09:57:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/serhsserveis.com\/wp-content\/uploads\/2018\/03\/Venta-de-Servicios-Sentimientos-Valores-01.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1431\" \/>\n\t<meta property=\"og:image:height\" content=\"950\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"rf\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rf\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/vender-servicios-sentimientos-valores-experiencias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/vender-servicios-sentimientos-valores-experiencias\\\/\"},\"author\":{\"name\":\"rf\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#\\\/schema\\\/person\\\/ed29406fe23d106405df24b321e0be26\"},\"headline\":\"Vender Servicios, sentimientos, valores, experiencias\",\"datePublished\":\"2018-04-05T18:06:47+00:00\",\"dateModified\":\"2019-06-03T09:57:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/vender-servicios-sentimientos-valores-experiencias\\\/\"},\"wordCount\":446,\"publisher\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/vender-servicios-sentimientos-valores-experiencias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serhsserveis.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Venta-de-Servicios-Sentimientos-Valores-01.png\",\"keywords\":[\"SENTIMIENTOS\",\"VALORES\",\"VENTA DE SERVICIOS\"],\"articleSection\":[\"BLOG\",\"Gesti\u00f3n de personas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/vender-servicios-sentimientos-valores-experiencias\\\/\",\"url\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/vender-servicios-sentimientos-valores-experiencias\\\/\",\"name\":\"Vender Servicios, sentimientos, valores, experiencias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/vender-servicios-sentimientos-valores-experiencias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/vender-servicios-sentimientos-valores-experiencias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/serhsserveis.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Venta-de-Servicios-Sentimientos-Valores-01.png\",\"datePublished\":\"2018-04-05T18:06:47+00:00\",\"dateModified\":\"2019-06-03T09:57:51+00:00\",\"description\":\"Campa\u00f1a de la renta 2017-2018. Haz la renta y consigue descuentos en seguros, servicios fiscal-contables y nuevas tecnolog\u00edas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/vender-servicios-sentimientos-valores-experiencias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/serhsserveis.com\\\/es\\\/vender-servicios-sentimientos-valores-experiencias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/vender-servicios-sentimientos-valores-experiencias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/serhsserveis.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Venta-de-Servicios-Sentimientos-Valores-01.png\",\"contentUrl\":\"https:\\\/\\\/serhsserveis.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Venta-de-Servicios-Sentimientos-Valores-01.png\",\"width\":1431,\"height\":950,\"caption\":\"Venta de Servicios, Sentimientos, Valores\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/vender-servicios-sentimientos-valores-experiencias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vender Servicios, sentimientos, valores, experiencias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#website\",\"url\":\"https:\\\/\\\/serhsserveis.com\\\/\",\"name\":\"SERHS Serveis\",\"description\":\"T&#039;ho posa f\u00e0cil\",\"publisher\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/serhsserveis.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#organization\",\"name\":\"SERHS Serveis\",\"url\":\"https:\\\/\\\/serhsserveis.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/serhsserveis.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/Logo-SERHS-Serveis-Serveis-integrals.png\",\"contentUrl\":\"https:\\\/\\\/serhsserveis.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/Logo-SERHS-Serveis-Serveis-integrals.png\",\"width\":120,\"height\":40,\"caption\":\"SERHS Serveis\"},\"image\":{\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SERHS-Serveis-914835645340740\\\/\",\"https:\\\/\\\/www.instagram.com\\\/serhsserveis\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/serhs-serveis\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCyY1p4E94vhubNiJb8yESgQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/serhsserveis.com\\\/#\\\/schema\\\/person\\\/ed29406fe23d106405df24b321e0be26\",\"name\":\"rf\",\"url\":\"https:\\\/\\\/serhsserveis.com\\\/es\\\/author\\\/rf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vender Servicios, sentimientos, valores, experiencias","description":"Campa\u00f1a de la renta 2017-2018. Haz la renta y consigue descuentos en seguros, servicios fiscal-contables y nuevas tecnolog\u00edas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/serhsserveis.com\/es\/vender-servicios-sentimientos-valores-experiencias\/","og_locale":"es_ES","og_type":"article","og_title":"Vender Servicios, sentimientos, valores, experiencias","og_description":"Campa\u00f1a de la renta 2017-2018. Haz la renta y consigue descuentos en seguros, servicios fiscal-contables y nuevas tecnolog\u00edas.","og_url":"https:\/\/serhsserveis.com\/es\/vender-servicios-sentimientos-valores-experiencias\/","og_site_name":"SERHS Serveis","article_publisher":"https:\/\/www.facebook.com\/SERHS-Serveis-914835645340740\/","article_published_time":"2018-04-05T18:06:47+00:00","article_modified_time":"2019-06-03T09:57:51+00:00","og_image":[{"width":1431,"height":950,"url":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2018\/03\/Venta-de-Servicios-Sentimientos-Valores-01.png","type":"image\/png"}],"author":"rf","twitter_misc":{"Escrito por":"rf","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/serhsserveis.com\/es\/vender-servicios-sentimientos-valores-experiencias\/#article","isPartOf":{"@id":"https:\/\/serhsserveis.com\/es\/vender-servicios-sentimientos-valores-experiencias\/"},"author":{"name":"rf","@id":"https:\/\/serhsserveis.com\/#\/schema\/person\/ed29406fe23d106405df24b321e0be26"},"headline":"Vender Servicios, sentimientos, valores, experiencias","datePublished":"2018-04-05T18:06:47+00:00","dateModified":"2019-06-03T09:57:51+00:00","mainEntityOfPage":{"@id":"https:\/\/serhsserveis.com\/es\/vender-servicios-sentimientos-valores-experiencias\/"},"wordCount":446,"publisher":{"@id":"https:\/\/serhsserveis.com\/#organization"},"image":{"@id":"https:\/\/serhsserveis.com\/es\/vender-servicios-sentimientos-valores-experiencias\/#primaryimage"},"thumbnailUrl":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2018\/03\/Venta-de-Servicios-Sentimientos-Valores-01.png","keywords":["SENTIMIENTOS","VALORES","VENTA DE SERVICIOS"],"articleSection":["BLOG","Gesti\u00f3n de personas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/serhsserveis.com\/es\/vender-servicios-sentimientos-valores-experiencias\/","url":"https:\/\/serhsserveis.com\/es\/vender-servicios-sentimientos-valores-experiencias\/","name":"Vender Servicios, sentimientos, valores, experiencias","isPartOf":{"@id":"https:\/\/serhsserveis.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/serhsserveis.com\/es\/vender-servicios-sentimientos-valores-experiencias\/#primaryimage"},"image":{"@id":"https:\/\/serhsserveis.com\/es\/vender-servicios-sentimientos-valores-experiencias\/#primaryimage"},"thumbnailUrl":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2018\/03\/Venta-de-Servicios-Sentimientos-Valores-01.png","datePublished":"2018-04-05T18:06:47+00:00","dateModified":"2019-06-03T09:57:51+00:00","description":"Campa\u00f1a de la renta 2017-2018. Haz la renta y consigue descuentos en seguros, servicios fiscal-contables y nuevas tecnolog\u00edas.","breadcrumb":{"@id":"https:\/\/serhsserveis.com\/es\/vender-servicios-sentimientos-valores-experiencias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/serhsserveis.com\/es\/vender-servicios-sentimientos-valores-experiencias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/serhsserveis.com\/es\/vender-servicios-sentimientos-valores-experiencias\/#primaryimage","url":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2018\/03\/Venta-de-Servicios-Sentimientos-Valores-01.png","contentUrl":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2018\/03\/Venta-de-Servicios-Sentimientos-Valores-01.png","width":1431,"height":950,"caption":"Venta de Servicios, Sentimientos, Valores"},{"@type":"BreadcrumbList","@id":"https:\/\/serhsserveis.com\/es\/vender-servicios-sentimientos-valores-experiencias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/serhsserveis.com\/es\/"},{"@type":"ListItem","position":2,"name":"Vender Servicios, sentimientos, valores, experiencias"}]},{"@type":"WebSite","@id":"https:\/\/serhsserveis.com\/#website","url":"https:\/\/serhsserveis.com\/","name":"SERHS Serveis","description":"T&#039;ho posa f\u00e0cil","publisher":{"@id":"https:\/\/serhsserveis.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/serhsserveis.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/serhsserveis.com\/#organization","name":"SERHS Serveis","url":"https:\/\/serhsserveis.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/serhsserveis.com\/#\/schema\/logo\/image\/","url":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2017\/09\/Logo-SERHS-Serveis-Serveis-integrals.png","contentUrl":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2017\/09\/Logo-SERHS-Serveis-Serveis-integrals.png","width":120,"height":40,"caption":"SERHS Serveis"},"image":{"@id":"https:\/\/serhsserveis.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SERHS-Serveis-914835645340740\/","https:\/\/www.instagram.com\/serhsserveis\/","https:\/\/www.linkedin.com\/company\/serhs-serveis","https:\/\/www.youtube.com\/channel\/UCyY1p4E94vhubNiJb8yESgQ"]},{"@type":"Person","@id":"https:\/\/serhsserveis.com\/#\/schema\/person\/ed29406fe23d106405df24b321e0be26","name":"rf","url":"https:\/\/serhsserveis.com\/es\/author\/rf\/"}]}},"jetpack_featured_media_url":"https:\/\/serhsserveis.com\/wp-content\/uploads\/2018\/03\/Venta-de-Servicios-Sentimientos-Valores-01.png","_links":{"self":[{"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/posts\/4573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/comments?post=4573"}],"version-history":[{"count":0,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/posts\/4573\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/media\/4602"}],"wp:attachment":[{"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/media?parent=4573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/categories?post=4573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/serhsserveis.com\/es\/wp-json\/wp\/v2\/tags?post=4573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}